{"id":103,"date":"2011-12-27T15:30:28","date_gmt":"2011-12-27T15:30:28","guid":{"rendered":"http:\/\/translator.ee\/?p=103"},"modified":"2016-05-09T20:46:26","modified_gmt":"2016-05-09T18:46:26","slug":"sissejuhatus","status":"publish","type":"post","link":"https:\/\/www.translator.ee\/de\/bottomleft\/sissejuhatus\/","title":{"rendered":""},"content":{"rendered":"<p>Ihr vereidigter \u00dcbersetzer f\u00fcr Estnisch-Deutsch, Deutsch-Russisch-Deutsch und Estnisch-Russisch in Tallinn! M\u00f6glich sind beglaubigte \u00dcbersetzungen, die am gleichen Tag ausgestellt werden k\u00f6nnen. Au\u00dferdem biete ich unbeglaubigte \u00dcbersetzungen aus dem Estnischen, Deutschen und Englischen ins Russische. Unbeglaubigte \u00dcbersetzungen k\u00f6nnen einfach per E-Mail bestellt werden. Falls ein Dokument ins Deutsche aus einer anderen Sprache \u00fcbersetzt und dies beglaubigt werden muss, finde ich f\u00fcr Sie einen vereidigten \u00dcbersetzer in Deutschland, \u00d6sterreich oder der Schweiz, wo in der Regel nur die \u00dcbersetzung eines vereidigten \u00dcbersetzers akzeptiert wird. Ich k\u00fcmmere mich auch um die Beantragung von Apostillen. Dar\u00fcber hinaus biete ich Beratung bei der \u00dcbersetzung von Dokumenten und bei mit deren Gebrauch verbundenen Fragen (z.B. Apostillen, Duplikate, Registerausz\u00fcge usw.). Die zu \u00fcbersetzenden Dokumente k\u00f6nnen Sie gern w\u00e4hrend der \u00fcblichen Gesch\u00e4ftszeiten von 9 bis 17 Uhr im \u00dcbersetzungsb\u00fcro &#8222;Kesklinna T\u00f5lkekeskus&#8220; in der <a href=\"https:\/\/www.google.ee\/maps\/place\/R%C3%A4vala+puiestee+6,+10145+Tallinn\/@59.4343551,24.7545466,17z\/data=!3m1!4b1!4m2!3m1!1s0x4692935fe4a9d5c1:0x1823790ffad8d5ad\" target=\"_blank\">R\u00e4vala-Str. 6<\/a> pers\u00f6nlich im Original vorbeibringen, als auch einwerfen, per Post oder Email zusenden. Sie k\u00f6nnen mich jeder Zeit anrufen und einen anderen Termin vereinbaren. In Eilf\u00e4llen auch <span style=\"color: #ff0000;\">24-Stunden-Service<\/span>.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ihr vereidigter \u00dcbersetzer f\u00fcr Estnisch-Deutsch, Deutsch-Russisch-Deutsch und Estnisch-Russisch in Tallinn! M\u00f6glich sind beglaubigte \u00dcbersetzungen, die am gleichen Tag ausgestellt werden k\u00f6nnen. Au\u00dferdem biete ich unbeglaubigte \u00dcbersetzungen aus dem Estnischen, Deutschen und Englischen ins Russische. Unbeglaubigte \u00dcbersetzungen k\u00f6nnen einfach per E-Mail &hellip; <a href=\"https:\/\/www.translator.ee\/de\/bottomleft\/sissejuhatus\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":2,"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.translator.ee\/de\/wp-json\/wp\/v2\/posts\/103"}],"collection":[{"href":"https:\/\/www.translator.ee\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.translator.ee\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.translator.ee\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.translator.ee\/de\/wp-json\/wp\/v2\/comments?post=103"}],"version-history":[{"count":42,"href":"https:\/\/www.translator.ee\/de\/wp-json\/wp\/v2\/posts\/103\/revisions"}],"predecessor-version":[{"id":765,"href":"https:\/\/www.translator.ee\/de\/wp-json\/wp\/v2\/posts\/103\/revisions\/765"}],"wp:attachment":[{"href":"https:\/\/www.translator.ee\/de\/wp-json\/wp\/v2\/media?parent=103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.translator.ee\/de\/wp-json\/wp\/v2\/categories?post=103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.translator.ee\/de\/wp-json\/wp\/v2\/tags?post=103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}